{"id":143,"date":"2008-04-07T08:42:00","date_gmt":"2008-04-07T08:42:00","guid":{"rendered":"http:\/\/www.tutego.de\/blog\/javainsel\/?p=143"},"modified":"2008-04-07T08:42:00","modified_gmt":"2008-04-07T08:42:00","slug":"thema-der-woche-apache-commons","status":"publish","type":"post","link":"https:\/\/www.tutego.de\/blog\/javainsel\/2008\/04\/thema-der-woche-apache-commons\/","title":{"rendered":"Thema der Woche: Apache Commons"},"content":{"rendered":"<p>Die Apache-Group hat mit ihren vielen Projekten irgendwann bemerkt, dass sie einige Dinge immer wieder programmieren. So ist nach und nach <a title=\"http:\/\/commons.apache.org\/\" href=\"http:\/\/commons.apache.org\/\">http:\/\/commons.apache.org\/<\/a> entstanden, ein Projekt, welches viele Hilfsklassen implementiert.<\/p>\n<ul>\n<li>Verschaffe einen groben \u00dcberblick \u00fcber alle Projekte von <a title=\"http:\/\/commons.apache.org\/\" href=\"http:\/\/commons.apache.org\/\">http:\/\/commons.apache.org\/<\/a>, wof\u00fcr sie da sind und sie leisten.<\/li>\n<\/ul>\n<p>Vertiefe in <a title=\"http:\/\/commons.apache.org\/io\/\" href=\"http:\/\/commons.apache.org\/io\/\">http:\/\/commons.apache.org\/io\/<\/a> und <a title=\"http:\/\/commons.apache.org\/lang\/\" href=\"http:\/\/commons.apache.org\/lang\/\">http:\/\/commons.apache.org\/lang\/<\/a> und schaue in die Typbeschreibung jeder Klasse\/Schnittstelle.<\/p>\n<ul>\n<li>Programme eine Beispielprogramm, bei dem die toString()-Methode generisch \u00fcber ToStringBuilder aufgebaut wird.<\/li>\n<li>Schreibe ein paar Demos, die Funktionen aus StringUtils, WordUtils nutzen.<\/li>\n<li>Kopiere eine Datei von einer Stelle zur anderen.<\/li>\n<li>Nutze passende Klassen\/Funktionen aus org.apache.commons.io.filefilter um in einem Vergleiche alle Dateien zu finden, die (\u00e4lter ein als gewisses Datum sind UND \u00fcber einer gewissen Gr\u00f6\u00dfe liegen) ODER (auf eine bestimmte Dateiendungen, wie doc oder rtf, enden).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Apache-Group hat mit ihren vielen Projekten irgendwann bemerkt, dass sie einige Dinge immer wieder programmieren. So ist nach und nach http:\/\/commons.apache.org\/ entstanden, ein Projekt, welches viele Hilfsklassen implementiert. Verschaffe einen groben \u00dcberblick \u00fcber alle Projekte von http:\/\/commons.apache.org\/, wof\u00fcr sie da sind und sie leisten. Vertiefe in http:\/\/commons.apache.org\/io\/ und http:\/\/commons.apache.org\/lang\/ und schaue in die Typbeschreibung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[13],"tags":[],"class_list":["post-143","post","type-post","status-publish","format-standard","hentry","category-die-wochentliche-dosis-java"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/comments?post=143"}],"version-history":[{"count":0,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts\/143\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/media?parent=143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/categories?post=143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/tags?post=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}