{"id":2460,"date":"2013-10-05T13:14:08","date_gmt":"2013-10-05T11:14:08","guid":{"rendered":"http:\/\/www.tutego.de\/blog\/javainsel\/?p=2460"},"modified":"2013-10-17T18:46:33","modified_gmt":"2013-10-17T16:46:33","slug":"gui-builder-fr-javafx-und-swing","status":"publish","type":"post","link":"https:\/\/www.tutego.de\/blog\/javainsel\/2013\/10\/gui-builder-fr-javafx-und-swing\/","title":{"rendered":"GUI-Builder f&uuml;r JavaFX und Swing"},"content":{"rendered":"<p>Mit einem GUI-Builder lassen sich grafische Oberfl\u00e4chen \u00fcber ein grafisches Werkzeug einfach aufbauen. In der Regel bietet ein GUI-Bilder eine Zeichenfl\u00e4che und eine Symbolleiste mit Komponenten, die per Drag and Drop angeordnet werden. Zentral bei dem Ansatz ist das WYSIWYG-Prinzip (What You See Is What You Get), dass n\u00e4mlich im Designschritt schon abzulesen ist, wie die fertige Oberfl\u00e4che aussieht.<\/p>\n<p>Ein GUI-Builder erzeugt eine Repr\u00e4sentation der grafischen Oberfl\u00e4che, die im Prinzip auch von Hand zu erstellen w\u00e4re \u2013 allerdings ist der Aufwand sehr gro\u00df und f\u00fcr jeden nachvollziehbar, der schon einmal in HMTL eine neue Tabellenspalte hinzugef\u00fchrt hat. Es gibt immer wieder Diskussion \u00fcber das F\u00fcr und Wider doch ist es wie mit allen Tools: richtig eingesetzt kann ein GUI-Builder viel Arbeit sparen.<\/p>\n<h3>GUI-Builder f\u00fcr JavaFX<\/h3>\n<p>Der JavaFX Scene Builder ist ein Werkzeug von Oracle und nennt sich selbst \u201eA Visual Layout Tool for JavaFX Applications\u201c. Er ist kein Teil vom JDK, sondern muss unter http:\/\/www.oracle.com\/technetwork\/java\/javafx\/tools\/index.html bezogen und installiert werden. Danach stehen komfortable Werkzeuge zum Entwurf von Oberfl\u00e4chen und deren Versch\u00f6nerung mit CSS nichts im Wege.<\/p>\n<p>NetBeans bietet von Haus aus Unterst\u00fctzung im Entwurf grafischer Oberfl\u00e4chen, denn ein GUI-Bilder ist integriert, und eine Zusatzinstallation ist nicht n\u00f6tig. Das gibt uns direkte M\u00f6glichkeiten, Swing und auch JavaFX spielerisch zu erfahren.<a href=\"file:\/\/\/C:\/Users\/Christian\/Dropbox\/Eigene Dokumente\/Insel\/#_ftn1_8106\" name=\"_ftnref1_8106\">[1]<\/a><\/p>\n<p>F\u00fcr Eclipse gibt es keinen speziellen GUI-Builder, das ist auch eigentlich gar nicht n\u00f6tig, denn der Scene Builder kann in Eclipse integriert werden.<a href=\"file:\/\/\/C:\/Users\/Christian\/Dropbox\/Eigene Dokumente\/Insel\/#_ftn2_8106\" name=\"_ftnref2_8106\">[2]<\/a> Zwar kein direkter WYSIWYG-Editor, aber immerhin ein Werkzeug im Umgang mit XML ist das quelloffenes Eclipse-Plugin e(fx)clipse unter http:\/\/efxclipse.org\/.<\/p>\n<h3>GUI-Builder f\u00fcr Swing<\/h3>\n<p>W\u00e4hrend NetBeans f\u00fcr Swing gute Unterst\u00fctzung mitbringt, ist bei Eclipse standardm\u00e4\u00dfig kein GUI-Builder integriert. Es gilt also, ein Plugin nachzuinstallieren. In den letzten Jahren kamen und gingen verschiedene GUI-Builder, aber letztendlich hat sich der WindowsBuilder (https:\/\/developers.google.com\/java-dev-tools\/wbpro\/) von Google als De-facto-Standard etabliert. \u00dcber den Update-Mechanismus von Eclipse wird er installiert. Eine Installationsanleitung findet sich auf der Webseite. Neben Swing nimmt der WindowsBuilder gleich noch GWT, SWT und XWT (Eclipse XML Window Toolkit) mit.<\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<p><a href=\"file:\/\/\/C:\/Users\/Christian\/Dropbox\/Eigene Dokumente\/Insel\/#_ftnref1_8106\" name=\"_ftn1_8106\">[1]<\/a> Didaktiker nennen das \u00bbexploratives Lernen\u00ab.<\/p>\n<p><a href=\"file:\/\/\/C:\/Users\/Christian\/Dropbox\/Eigene Dokumente\/Insel\/#_ftnref2_8106\" name=\"_ftn2_8106\">[2]<\/a> http:\/\/docs.oracle.com\/javafx\/scenebuilder\/1\/use_java_ides\/sb-with-eclipse.htm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit einem GUI-Builder lassen sich grafische Oberfl\u00e4chen \u00fcber ein grafisches Werkzeug einfach aufbauen. In der Regel bietet ein GUI-Bilder eine Zeichenfl\u00e4che und eine Symbolleiste mit Komponenten, die per Drag and Drop angeordnet werden. Zentral bei dem Ansatz ist das WYSIWYG-Prinzip (What You See Is What You Get), dass n\u00e4mlich im Designschritt schon abzulesen ist, wie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[7,62,10],"tags":[8,34],"class_list":["post-2460","post","type-post","status-publish","format-standard","hentry","category-entwicklungsumgebung","category-javafx","category-swing","tag-eclipse","tag-netbeans"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts\/2460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/comments?post=2460"}],"version-history":[{"count":2,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts\/2460\/revisions"}],"predecessor-version":[{"id":2476,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/posts\/2460\/revisions\/2476"}],"wp:attachment":[{"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/media?parent=2460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/categories?post=2460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tutego.de\/blog\/javainsel\/wp-json\/wp\/v2\/tags?post=2460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}